{"id":15925,"date":"2026-07-14T19:47:02","date_gmt":"2026-07-14T19:47:02","guid":{"rendered":"https:\/\/andradenetvendas.com.br\/index.php\/item\/logitech-c-u0008-wireless-usb-reciever-d-2\/"},"modified":"2026-07-14T19:47:02","modified_gmt":"2026-07-14T19:47:02","slug":"logitech-c-u0008-wireless-usb-reciever-d-2","status":"publish","type":"itempress_product","link":"https:\/\/andradenetvendas.com.br\/index.php\/item\/logitech-c-u0008-wireless-usb-reciever-d-2\/","title":{"rendered":"Logitech C-U0008 Wireless USB Reciever Dongle"},"content":{"rendered":"<p>It is plug-and-play and provides a stable connection with a simple and efficient setup. Compatibility: Logitech devices (mice, keyboards, etc.). Type: Wireless USB Receiver. Connectivity: 2.4 GHz wireless.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"itempress_category":[171],"itempress_tag":[30,116,8447,26750,344,205,203,347],"class_list":["post-15925","itempress_product","type-itempress_product","status-publish","hentry","itempress_category-cat-44999","itempress_tag-black","itempress_tag-china","itempress_tag-dongle","itempress_tag-logi-logitech-c-u0008","itempress_tag-logitech","itempress_tag-usb-2-0","itempress_tag-usb-wireless","itempress_tag-wireless-usb-c"],"_links":{"self":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_product\/15925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_product"}],"about":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/types\/itempress_product"}],"replies":[{"embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=15925"}],"wp:attachment":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=15925"}],"wp:term":[{"taxonomy":"itempress_category","embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_category?post=15925"},{"taxonomy":"itempress_tag","embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_tag?post=15925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}