{"id":7050,"date":"2026-07-14T13:25:43","date_gmt":"2026-07-14T13:25:43","guid":{"rendered":"https:\/\/andradenetvendas.com.br\/index.php\/item\/viewsonic-va2746mh-led-27-full-hd-monit\/"},"modified":"2026-07-14T13:27:19","modified_gmt":"2026-07-14T13:27:19","slug":"viewsonic-va2746mh-led-27-full-hd-monit","status":"publish","type":"itempress_product","link":"https:\/\/andradenetvendas.com.br\/index.php\/item\/viewsonic-va2746mh-led-27-full-hd-monit\/","title":{"rendered":"ViewSonic VA2746mh-LED 27&#8243; Full HD Monitor &#8211; HDMI VGA Built-In Speakers"},"content":{"rendered":"<p>ViewSonic VA2746mh-LED 27&#8243; Widescreen LED Monitor. ViewSonic VA2746mh-LED Monitor. HDMI Cable. 1 x 3.5mm Audio In (Green). What\u2019s Included.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"itempress_category":[2754],"itempress_tag":[2600,54,2979,4717,4306,613,30,144,4304,23,14780,14779,14667,14781],"class_list":["post-7050","itempress_product","type-itempress_product","status-publish","hentry","itempress_category-cat-80053","itempress_tag-2600","itempress_tag-1920-x-1080","itempress_tag-27-in","itempress_tag-300-cd-m2","itempress_tag-5-ms","itempress_tag-75-hz","itempress_tag-black","itempress_tag-built-in-speakers","itempress_tag-led-backlight","itempress_tag-unit","itempress_tag-va2746mh-led","itempress_tag-va2746mhled","itempress_tag-viewsonic","itempress_tag-viewsonic-va"],"_links":{"self":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_product\/7050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_product"}],"about":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/types\/itempress_product"}],"replies":[{"embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7050"}],"wp:attachment":[{"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7050"}],"wp:term":[{"taxonomy":"itempress_category","embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_category?post=7050"},{"taxonomy":"itempress_tag","embeddable":true,"href":"https:\/\/andradenetvendas.com.br\/index.php\/wp-json\/wp\/v2\/itempress_tag?post=7050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}